{"id":20509,"date":"2019-11-20T11:17:22","date_gmt":"2019-11-20T09:17:22","guid":{"rendered":"https:\/\/dermalcosmetics.com\/?post_type=product&#038;p=20509"},"modified":"2023-08-01T10:04:16","modified_gmt":"2023-08-01T07:04:16","slug":"hyafilia-classic-plus-lidocaine-1-x-1ml","status":"publish","type":"product","link":"https:\/\/dermalcosmetics.com\/fr\/produit\/hyafilia-classic-plus-lidocaine-1-x-1ml\/","title":{"rendered":"Hyafilia Classic Plus Lidoca\u00efne (1 x 1 ml)"},"content":{"rendered":"<h3>Remplisseur de peau de premier ordre qui corrige les rides mod\u00e9r\u00e9es<\/h3>\n<p>Les rides et ridules de taille moyenne telles que les sillons nasog\u00e9niens, les rides glabellaires, les rides du fumeur, etc. peuvent \u00eatre \u00e9limin\u00e9es avec succ\u00e8s apr\u00e8s une seule s\u00e9ance d&#039;injection avec HyaFilia Classic avec Lidocaine Plus. Ce produit r\u00e9volutionnaire a une structure hybride (un m\u00e9lange de HA \u00e0 la fois r\u00e9ticul\u00e9 et non r\u00e9ticul\u00e9) et de ce fait, il offre des r\u00e9sultats imm\u00e9diats qui restent visibles jusqu&#039;\u00e0 une ann\u00e9e compl\u00e8te. Officiellement reconnu comme un <u>Dispositif m\u00e9dical de classe III<\/u>, cette injection de comblement dermique de premier ordre sera compl\u00e8tement excr\u00e9t\u00e9e du corps du patient, ce qui la rend incroyablement s\u00fbre pour une utilisation r\u00e9guli\u00e8re.<\/p>\n<h3>Quelles zones du corps peuvent \u00eatre trait\u00e9es avec HyaFilia Classic with Lidocaine Plus ?<\/h3>\n<p>HyaFilia Classic avec Lidoca\u00efne Plus doit \u00eatre <em>administr\u00e9 par injection<\/em> dans la couche moyenne de la peau par un chirurgien plasticien form\u00e9 et certifi\u00e9. Avec sa concentration id\u00e9ale en HA de 20 mg\/ml et sa granulom\u00e9trie moyenne de 500 \u00b5m, il peut \u00eatre utilis\u00e9 en toute s\u00e9curit\u00e9 pour la correction et le rajeunissement mini-invasifs du visage et de diff\u00e9rentes parties du corps.<\/p>\n<ul>\n<li>Visage<\/li>\n<li>Cou<\/li>\n<li>D\u00e9collet\u00e9<\/li>\n<li>Dos des mains (dos des mains)<\/li>\n<\/ul>\n<p>La long\u00e9vit\u00e9 des effets offerte par ce produit haut de gamme est <u>jusqu&#039;\u00e0 12 mois<\/u>, quelle que soit la zone de traitement cible. Des s\u00e9ances de suivi doivent \u00eatre programm\u00e9es par les cliniciens tous les quelques mois si le patient veut pr\u00e9server son apparence rajeunie.<\/p>","protected":false},"excerpt":{"rendered":"<p>Long\u00e9vit\u00e9 impressionnante des effets, s\u00e9curit\u00e9 garantie, excellente qualit\u00e9 - ce ne sont l\u00e0 que quelques-uns des avantages de l&#039;utilisation de HyaFilia Classic avec Lidocaine Plus. C&#039;est l&#039;un des plus <strong>produits de comblement de la peau fiables<\/strong> \u00e0 base d&#039;acide hyaluronique. Fabriqu\u00e9 par CHA Meditech et distribu\u00e9 par nos soins, de Dermal Cosmetics, et il est appr\u00e9ci\u00e9 pour sa capacit\u00e9 \u00e0 <em>\u00e9liminer rapidement les rides et ridules moyennes<\/em>. Il contient une petite quantit\u00e9 de lidoca\u00efne, rendant toute proc\u00e9dure anti-\u00e2ge avec le 100% indolore.<\/p>","protected":false},"featured_media":20512,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[145,207,175],"product_tag":[210],"class_list":["post-20509","product","type-product","status-publish","has-post-thumbnail","product_cat-dermal-fillers","product_cat-holiday-sale","product_cat-hyafilia","product_tag-210","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hyafilia Classic Plus Lidocaine (1 x 1ml) - Dermal Cosmetics<\/title>\n<meta name=\"description\" content=\"Sold by Dermal Cosmetics, HyaFilia Classic with Lidocaine Plus safely removes medium lines. HyaFilia Classic with Lidocaine Plus is a top-notch HA filler.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dermalcosmetics.com\/fr\/produit\/hyafilia-classic-plus-lidocaine-1-x-1ml\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hyafilia Classic Plus Lidocaine (1 x 1ml) - Dermal Cosmetics\" \/>\n<meta property=\"og:description\" content=\"Sold by Dermal Cosmetics, HyaFilia Classic with Lidocaine Plus safely removes medium lines. HyaFilia Classic with Lidocaine Plus is a top-notch HA filler.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dermalcosmetics.com\/fr\/produit\/hyafilia-classic-plus-lidocaine-1-x-1ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Dermal Cosmetics\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-01T07:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.dermalcosmetics.com\/wp-content\/uploads\/2019\/11\/Hyafilia-Classic-Plus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/\",\"url\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/\",\"name\":\"Hyafilia Classic Plus Lidocaine (1 x 1ml) - Dermal Cosmetics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dermalcosmetics.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Hyafilia-Classic-Plus.jpg\",\"datePublished\":\"2019-11-20T09:17:22+00:00\",\"dateModified\":\"2023-08-01T07:04:16+00:00\",\"description\":\"Sold by Dermal Cosmetics, HyaFilia Classic with Lidocaine Plus safely removes medium lines. HyaFilia Classic with Lidocaine Plus is a top-notch HA filler.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dermalcosmetics.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Hyafilia-Classic-Plus.jpg\",\"contentUrl\":\"https:\\\/\\\/dermalcosmetics.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Hyafilia-Classic-Plus.jpg\",\"width\":600,\"height\":600,\"caption\":\"Hyafilia Classic Plus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/product\\\/hyafilia-classic-plus-lidocaine-1-x-1ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dermalcosmetics.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dermalcosmetics.com\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hyafilia Classic Plus Lidocaine (1 x 1ml)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dermalcosmetics.com\\\/#website\",\"url\":\"https:\\\/\\\/dermalcosmetics.com\\\/\",\"name\":\"Dermal Cosmetics\",\"description\":\"High Quality Dermal and Cosmetic Products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dermalcosmetics.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hyafilia Classic Plus Lidoca\u00efne (1 x 1ml) - Cosm\u00e9tique Dermique","description":"Vendu par Dermal Cosmetics, HyaFilia Classic avec Lidocaine Plus \u00e9limine en toute s\u00e9curit\u00e9 les ridules moyennes. HyaFilia Classic avec Lidocaine Plus est un agent de remplissage HA de premier ordre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dermalcosmetics.com\/fr\/produit\/hyafilia-classic-plus-lidocaine-1-x-1ml\/","og_locale":"fr_FR","og_type":"article","og_title":"Hyafilia Classic Plus Lidocaine (1 x 1ml) - Dermal Cosmetics","og_description":"Sold by Dermal Cosmetics, HyaFilia Classic with Lidocaine Plus safely removes medium lines. HyaFilia Classic with Lidocaine Plus is a top-notch HA filler.","og_url":"https:\/\/dermalcosmetics.com\/fr\/produit\/hyafilia-classic-plus-lidocaine-1-x-1ml\/","og_site_name":"Dermal Cosmetics","article_modified_time":"2023-08-01T07:04:16+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/cdn.dermalcosmetics.com\/wp-content\/uploads\/2019\/11\/Hyafilia-Classic-Plus.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/","url":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/","name":"Hyafilia Classic Plus Lidoca\u00efne (1 x 1ml) - Cosm\u00e9tique Dermique","isPartOf":{"@id":"https:\/\/dermalcosmetics.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/#primaryimage"},"image":{"@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.dermalcosmetics.com\/wp-content\/uploads\/2019\/11\/Hyafilia-Classic-Plus.jpg","datePublished":"2019-11-20T09:17:22+00:00","dateModified":"2023-08-01T07:04:16+00:00","description":"Vendu par Dermal Cosmetics, HyaFilia Classic avec Lidocaine Plus \u00e9limine en toute s\u00e9curit\u00e9 les ridules moyennes. HyaFilia Classic avec Lidocaine Plus est un agent de remplissage HA de premier ordre.","breadcrumb":{"@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/#primaryimage","url":"https:\/\/cdn.dermalcosmetics.com\/wp-content\/uploads\/2019\/11\/Hyafilia-Classic-Plus.jpg","contentUrl":"https:\/\/cdn.dermalcosmetics.com\/wp-content\/uploads\/2019\/11\/Hyafilia-Classic-Plus.jpg","width":600,"height":600,"caption":"Hyafilia Classic Plus"},{"@type":"BreadcrumbList","@id":"https:\/\/dermalcosmetics.com\/product\/hyafilia-classic-plus-lidocaine-1-x-1ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dermalcosmetics.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dermalcosmetics.com\/store\/"},{"@type":"ListItem","position":3,"name":"Hyafilia Classic Plus Lidocaine (1 x 1ml)"}]},{"@type":"WebSite","@id":"https:\/\/dermalcosmetics.com\/#website","url":"https:\/\/dermalcosmetics.com\/","name":"Cosm\u00e9tiques cutan\u00e9s","description":"Produits cutan\u00e9s et cosm\u00e9tiques de haute qualit\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dermalcosmetics.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/product\/20509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/comments?post=20509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/media\/20512"}],"wp:attachment":[{"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/media?parent=20509"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/product_brand?post=20509"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/product_cat?post=20509"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dermalcosmetics.com\/fr\/wp-json\/wp\/v2\/product_tag?post=20509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}